{"id":3397,"date":"2026-07-15T09:49:39","date_gmt":"2026-07-15T08:49:39","guid":{"rendered":"https:\/\/www.websyte.ch\/wordpress\/?p=3397"},"modified":"2026-07-15T09:49:39","modified_gmt":"2026-07-15T08:49:39","slug":"scuol-val-s-charl","status":"publish","type":"post","link":"https:\/\/www.websyte.ch\/wordpress\/archive\/3397","title":{"rendered":"Scuol &amp; Val S-charl"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"771\" height=\"1024\" src=\"https:\/\/www.websyte.ch\/wordpress\/wp-content\/uploads\/2026\/07\/PXL_20260711_070557218-771x1024.jpg\" alt=\"\" class=\"wp-image-3391\" srcset=\"https:\/\/www.websyte.ch\/wordpress\/wp-content\/uploads\/2026\/07\/PXL_20260711_070557218-771x1024.jpg 771w, https:\/\/www.websyte.ch\/wordpress\/wp-content\/uploads\/2026\/07\/PXL_20260711_070557218-226x300.jpg 226w, https:\/\/www.websyte.ch\/wordpress\/wp-content\/uploads\/2026\/07\/PXL_20260711_070557218-768x1020.jpg 768w, https:\/\/www.websyte.ch\/wordpress\/wp-content\/uploads\/2026\/07\/PXL_20260711_070557218-1157x1536.jpg 1157w, https:\/\/www.websyte.ch\/wordpress\/wp-content\/uploads\/2026\/07\/PXL_20260711_070557218-1542x2048.jpg 1542w, https:\/\/www.websyte.ch\/wordpress\/wp-content\/uploads\/2026\/07\/PXL_20260711_070557218-1200x1594.jpg 1200w, https:\/\/www.websyte.ch\/wordpress\/wp-content\/uploads\/2026\/07\/PXL_20260711_070557218-1860x2470.jpg 1860w, https:\/\/www.websyte.ch\/wordpress\/wp-content\/uploads\/2026\/07\/PXL_20260711_070557218-scaled.jpg 1928w\" sizes=\"auto, (max-width: 771px) 100vw, 771px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"771\" src=\"https:\/\/www.websyte.ch\/wordpress\/wp-content\/uploads\/2026\/07\/PXL_20260711_191424544-1024x771.jpg\" alt=\"\" class=\"wp-image-3396\" srcset=\"https:\/\/www.websyte.ch\/wordpress\/wp-content\/uploads\/2026\/07\/PXL_20260711_191424544-1024x771.jpg 1024w, https:\/\/www.websyte.ch\/wordpress\/wp-content\/uploads\/2026\/07\/PXL_20260711_191424544-300x226.jpg 300w, https:\/\/www.websyte.ch\/wordpress\/wp-content\/uploads\/2026\/07\/PXL_20260711_191424544-768x578.jpg 768w, https:\/\/www.websyte.ch\/wordpress\/wp-content\/uploads\/2026\/07\/PXL_20260711_191424544-1536x1157.jpg 1536w, https:\/\/www.websyte.ch\/wordpress\/wp-content\/uploads\/2026\/07\/PXL_20260711_191424544-2048x1542.jpg 2048w, https:\/\/www.websyte.ch\/wordpress\/wp-content\/uploads\/2026\/07\/PXL_20260711_191424544-1200x904.jpg 1200w, https:\/\/www.websyte.ch\/wordpress\/wp-content\/uploads\/2026\/07\/PXL_20260711_191424544-1860x1400.jpg 1860w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"771\" height=\"1024\" src=\"https:\/\/www.websyte.ch\/wordpress\/wp-content\/uploads\/2026\/07\/PXL_20260711_070605099-771x1024.jpg\" alt=\"\" class=\"wp-image-3392\" srcset=\"https:\/\/www.websyte.ch\/wordpress\/wp-content\/uploads\/2026\/07\/PXL_20260711_070605099-771x1024.jpg 771w, https:\/\/www.websyte.ch\/wordpress\/wp-content\/uploads\/2026\/07\/PXL_20260711_070605099-226x300.jpg 226w, https:\/\/www.websyte.ch\/wordpress\/wp-content\/uploads\/2026\/07\/PXL_20260711_070605099-768x1020.jpg 768w, https:\/\/www.websyte.ch\/wordpress\/wp-content\/uploads\/2026\/07\/PXL_20260711_070605099-1157x1536.jpg 1157w, https:\/\/www.websyte.ch\/wordpress\/wp-content\/uploads\/2026\/07\/PXL_20260711_070605099-1542x2048.jpg 1542w, https:\/\/www.websyte.ch\/wordpress\/wp-content\/uploads\/2026\/07\/PXL_20260711_070605099-1200x1594.jpg 1200w, https:\/\/www.websyte.ch\/wordpress\/wp-content\/uploads\/2026\/07\/PXL_20260711_070605099-1860x2470.jpg 1860w, https:\/\/www.websyte.ch\/wordpress\/wp-content\/uploads\/2026\/07\/PXL_20260711_070605099-scaled.jpg 1928w\" sizes=\"auto, (max-width: 771px) 100vw, 771px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"771\" src=\"https:\/\/www.websyte.ch\/wordpress\/wp-content\/uploads\/2026\/07\/PXL_20260711_082314158-1024x771.jpg\" alt=\"\" class=\"wp-image-3393\" srcset=\"https:\/\/www.websyte.ch\/wordpress\/wp-content\/uploads\/2026\/07\/PXL_20260711_082314158-1024x771.jpg 1024w, https:\/\/www.websyte.ch\/wordpress\/wp-content\/uploads\/2026\/07\/PXL_20260711_082314158-300x226.jpg 300w, https:\/\/www.websyte.ch\/wordpress\/wp-content\/uploads\/2026\/07\/PXL_20260711_082314158-768x578.jpg 768w, https:\/\/www.websyte.ch\/wordpress\/wp-content\/uploads\/2026\/07\/PXL_20260711_082314158-1536x1157.jpg 1536w, https:\/\/www.websyte.ch\/wordpress\/wp-content\/uploads\/2026\/07\/PXL_20260711_082314158-2048x1542.jpg 2048w, https:\/\/www.websyte.ch\/wordpress\/wp-content\/uploads\/2026\/07\/PXL_20260711_082314158-1200x904.jpg 1200w, https:\/\/www.websyte.ch\/wordpress\/wp-content\/uploads\/2026\/07\/PXL_20260711_082314158-1860x1400.jpg 1860w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"771\" src=\"https:\/\/www.websyte.ch\/wordpress\/wp-content\/uploads\/2026\/07\/PXL_20260711_082705804-1024x771.jpg\" alt=\"\" class=\"wp-image-3394\" srcset=\"https:\/\/www.websyte.ch\/wordpress\/wp-content\/uploads\/2026\/07\/PXL_20260711_082705804-1024x771.jpg 1024w, https:\/\/www.websyte.ch\/wordpress\/wp-content\/uploads\/2026\/07\/PXL_20260711_082705804-300x226.jpg 300w, https:\/\/www.websyte.ch\/wordpress\/wp-content\/uploads\/2026\/07\/PXL_20260711_082705804-768x578.jpg 768w, https:\/\/www.websyte.ch\/wordpress\/wp-content\/uploads\/2026\/07\/PXL_20260711_082705804-1536x1157.jpg 1536w, https:\/\/www.websyte.ch\/wordpress\/wp-content\/uploads\/2026\/07\/PXL_20260711_082705804-2048x1542.jpg 2048w, https:\/\/www.websyte.ch\/wordpress\/wp-content\/uploads\/2026\/07\/PXL_20260711_082705804-1200x904.jpg 1200w, https:\/\/www.websyte.ch\/wordpress\/wp-content\/uploads\/2026\/07\/PXL_20260711_082705804-1860x1400.jpg 1860w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"771\" height=\"1024\" src=\"https:\/\/www.websyte.ch\/wordpress\/wp-content\/uploads\/2026\/07\/PXL_20260711_124308807-771x1024.jpg\" alt=\"\" class=\"wp-image-3395\" srcset=\"https:\/\/www.websyte.ch\/wordpress\/wp-content\/uploads\/2026\/07\/PXL_20260711_124308807-771x1024.jpg 771w, https:\/\/www.websyte.ch\/wordpress\/wp-content\/uploads\/2026\/07\/PXL_20260711_124308807-226x300.jpg 226w, https:\/\/www.websyte.ch\/wordpress\/wp-content\/uploads\/2026\/07\/PXL_20260711_124308807-768x1020.jpg 768w, https:\/\/www.websyte.ch\/wordpress\/wp-content\/uploads\/2026\/07\/PXL_20260711_124308807-1157x1536.jpg 1157w, https:\/\/www.websyte.ch\/wordpress\/wp-content\/uploads\/2026\/07\/PXL_20260711_124308807-1542x2048.jpg 1542w, https:\/\/www.websyte.ch\/wordpress\/wp-content\/uploads\/2026\/07\/PXL_20260711_124308807-1200x1594.jpg 1200w, https:\/\/www.websyte.ch\/wordpress\/wp-content\/uploads\/2026\/07\/PXL_20260711_124308807-1860x2470.jpg 1860w, https:\/\/www.websyte.ch\/wordpress\/wp-content\/uploads\/2026\/07\/PXL_20260711_124308807-scaled.jpg 1928w\" sizes=\"auto, (max-width: 771px) 100vw, 771px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":71,"featured_media":3396,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-3397","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lebensalltag","has-thumbnail"],"_links":{"self":[{"href":"https:\/\/www.websyte.ch\/wordpress\/wp-json\/wp\/v2\/posts\/3397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.websyte.ch\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.websyte.ch\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.websyte.ch\/wordpress\/wp-json\/wp\/v2\/users\/71"}],"replies":[{"embeddable":true,"href":"https:\/\/www.websyte.ch\/wordpress\/wp-json\/wp\/v2\/comments?post=3397"}],"version-history":[{"count":1,"href":"https:\/\/www.websyte.ch\/wordpress\/wp-json\/wp\/v2\/posts\/3397\/revisions"}],"predecessor-version":[{"id":3398,"href":"https:\/\/www.websyte.ch\/wordpress\/wp-json\/wp\/v2\/posts\/3397\/revisions\/3398"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.websyte.ch\/wordpress\/wp-json\/wp\/v2\/media\/3396"}],"wp:attachment":[{"href":"https:\/\/www.websyte.ch\/wordpress\/wp-json\/wp\/v2\/media?parent=3397"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.websyte.ch\/wordpress\/wp-json\/wp\/v2\/categories?post=3397"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.websyte.ch\/wordpress\/wp-json\/wp\/v2\/tags?post=3397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}